{"id":19581,"date":"2026-01-03T09:07:34","date_gmt":"2026-01-03T12:07:34","guid":{"rendered":"https:\/\/www.mistol.com.ar\/shop\/producto\/cargador-inalambrico-qi-para-celular\/"},"modified":"2026-04-10T20:01:06","modified_gmt":"2026-04-10T23:01:06","slug":"cargador-inalambrico-qi-para-celular","status":"publish","type":"product","link":"https:\/\/www.mistol.com.ar\/shop\/producto\/cargador-inalambrico-qi-para-celular\/","title":{"rendered":"Cargador Inal\u00e1mbrico Qi para Celular"},"content":{"rendered":"<p>El plato cargador tiene una salida micro USB el cual tiene que estar conectado a cualquier USB de una computadora o a un enchufe a 220V. (Incluye el cable USB para conectarlo pero no incluye enchufe a 220V, podes usar el de tu celular).<br \/>\n* Compatible con celulares con tecnolog\u00eda Qi de f\u00e1brica.<br \/>\n* Se apoya directamente en el plato (Funciona apoyado a una distancia hasta 4-10mm)<br \/>\n* Impresi\u00f3n Full Color con tintas UV<\/p>\n<p>Carga de dispositivo v\u00eda inducci\u00f3n &#8211; Con entrada 5V\/2A &#8211; Potencia de carga de 5W &#8211; Incluye cable USB\/micro USB para cargar &#8211; Solamente compatible con smartphones con tecnolog\u00eda de carga inal\u00e1mbrica.<br \/>\nMedidas: \u00f8100 x 10 mm<br \/>\nImpresi\u00f3n de Logo: Impresi\u00f3n Full Color Tintas UV<br \/>\n\u00c1rea de Impresi\u00f3n: 3,5 cm x 2,5 cm<br \/>\nMateriales principales: Pl\u00e1stico<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El plato cargador tiene una salida micro USB el cual tiene que estar conectado a cualquier USB de una computadora o a un enchufe a 220V. (Incluye el cable USB para conectarlo pero no incluye enchufe a 220V, podes usar el de tu celular).<br \/>\n* Compatible con celulares con tecnolog\u00eda Qi de f\u00e1brica.<br \/>\n* Se apoya directamente en el plato (Funciona apoyado a una distancia hasta 4-10mm)<br \/>\n* Impresi\u00f3n Full Color con tintas UV<\/p>\n","protected":false},"featured_media":2133,"template":"","meta":[],"product_brand":[],"product_cat":[747],"product_tag":[],"class_list":["post-19581","product","type-product","status-publish","has-post-thumbnail","product_cat-novedades","pa_custom-personalizacion-full-color","pa_custom-sin-personalizacion","first","instock","shipping-taxable","product-type-variable"],"_links":{"self":[{"href":"https:\/\/www.mistol.com.ar\/shop\/wp-json\/wp\/v2\/product\/19581","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mistol.com.ar\/shop\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.mistol.com.ar\/shop\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mistol.com.ar\/shop\/wp-json\/wp\/v2\/media\/2133"}],"wp:attachment":[{"href":"https:\/\/www.mistol.com.ar\/shop\/wp-json\/wp\/v2\/media?parent=19581"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.mistol.com.ar\/shop\/wp-json\/wp\/v2\/product_brand?post=19581"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.mistol.com.ar\/shop\/wp-json\/wp\/v2\/product_cat?post=19581"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.mistol.com.ar\/shop\/wp-json\/wp\/v2\/product_tag?post=19581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}