{"id":14910,"date":"2025-05-08T18:34:01","date_gmt":"2025-05-08T21:34:01","guid":{"rendered":"https:\/\/www.mistol.com.ar\/shop\/producto\/jarro-horizon\/"},"modified":"2026-04-27T13:07:45","modified_gmt":"2026-04-27T16:07:45","slug":"jarro-horizon","status":"publish","type":"product","link":"https:\/\/www.mistol.com.ar\/shop\/producto\/jarro-horizon\/","title":{"rendered":"Jarro Horizon"},"content":{"rendered":"<p>Jarro de 600 ml fabricado en doble pared de acero inoxidable, dise\u00f1ado para mantener la temperatura ideal, ya sea fr\u00eda o caliente. Su tapa de PP incluye un destapador de botellas, combinando estilo y funcionalidad, perfecto para cualquier ocasi\u00f3n.<br \/>\nProducto libre de BPA, aprobado por el I.N.A.L. para el contacto con alimentos.<br \/>\nPampa Spirit<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jarro de 600 ml fabricado en doble pared de acero inoxidable, dise\u00f1ado para mantener la temperatura ideal, ya sea fr\u00eda o caliente. Su tapa de PP incluye un destapador de botellas, combinando estilo y funcionalidad, perfecto para cualquier ocasi\u00f3n. Producto libre de BPA, aprobado por el I.N.A.L. para el contacto con alimentos. Pampa Spirit<\/p>\n","protected":false},"featured_media":15933,"template":"","meta":[],"product_brand":[1013],"product_cat":[57,191],"product_tag":[],"class_list":["post-14910","product","type-product","status-publish","has-post-thumbnail","product_brand-pampa-spirit","product_cat-2025-novedades","product_cat-botellas-tazas-y-mates-2","first","instock","shipping-taxable","product-type-variable"],"_links":{"self":[{"href":"https:\/\/www.mistol.com.ar\/shop\/wp-json\/wp\/v2\/product\/14910","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mistol.com.ar\/shop\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.mistol.com.ar\/shop\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mistol.com.ar\/shop\/wp-json\/wp\/v2\/media\/15933"}],"wp:attachment":[{"href":"https:\/\/www.mistol.com.ar\/shop\/wp-json\/wp\/v2\/media?parent=14910"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.mistol.com.ar\/shop\/wp-json\/wp\/v2\/product_brand?post=14910"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.mistol.com.ar\/shop\/wp-json\/wp\/v2\/product_cat?post=14910"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.mistol.com.ar\/shop\/wp-json\/wp\/v2\/product_tag?post=14910"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}